<a class="changeslider" href="#">
</a>

       
       
                     <div class="slider__new__cus fixes__on__custom__slider__new">

                            <div class="secound__slider__full__max new__updated__slider">
                  <div class="fixed__height__custom__title fix__new__slider">
                      <div class="separate__header__20">
                    <p class="big__nr__testimonial">1 </p>
                  </div>
                    <div class="separate__header__80">
                <h3 class="header__title__custom__slider__new">  Sistema de polimento com diamante em dois estágios </h3>
                  <p class="subtitle__text__custom__slider"> Utilização fácil e eficiente em todas as cerâmicas </p>
                </div>
              </div>
                <div class="secound__slider update__secound__slider">

                  
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.1-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Estágio 1 pré-polimento, Granulação: smooth, Aparência: brilho sedoso </p>
                                         </div>
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.2-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Estágio 2 polimento de alto brilho, Granulação: gloss, Aparência: alto brilho </p>
                                         </div>
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-1.3-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new">  </p>
                                         </div>
                                 
                               


           </div>
         </div>
                            <div class="secound__slider__full__max new__updated__slider">
                  <div class="fixed__height__custom__title fix__new__slider">
                      <div class="separate__header__20">
                    <p class="big__nr__testimonial">2 </p>
                  </div>
                    <div class="separate__header__80">
                <h3 class="header__title__custom__slider__new">  Polidor de borracha de dimensões estáveis com diamantes intercalados </h3>
                  <p class="subtitle__text__custom__slider"> Resultado de brilho de aparência natural com longa durabilidade </p>
                </div>
              </div>
                <div class="secound__slider update__secound__slider">

                  
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-2-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Resultados de brilho espelhado, com aparência natural </p>
                                         </div>
                                 
                               


           </div>
         </div>
                            <div class="secound__slider__full__max new__updated__slider">
                  <div class="fixed__height__custom__title fix__new__slider">
                      <div class="separate__header__20">
                    <p class="big__nr__testimonial">3 </p>
                  </div>
                    <div class="separate__header__80">
                <h3 class="header__title__custom__slider__new">  Três formatos compatíveis entre si e uma pasta </h3>
                  <p class="subtitle__text__custom__slider"> Resultados de polimento ideais, independentemente da estrutura e da superfície </p>
                </div>
              </div>
                <div class="secound__slider update__secound__slider">

                  
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.1-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Turn 18 para superfícies </p>
                                         </div>
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.2-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Twist 17 para superfícies e fissuras </p>
                                         </div>
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.3-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Tip 5 para superfícies e fissuras </p>
                                         </div>
                                 
                                   <div class="full__secound__slider__custom new__slider__fix">
                                    <img width="960" height="640" src="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-960x640.png" class="attachment-products_custom_cropped size-products_custom_cropped" alt="" srcset="https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4.png 960w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-580x387.png 580w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-768x512.png 768w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-900x600.png 900w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-600x400.png 600w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-90x60.png 90w, https://sagemax.com/wp-content/uploads/2022/09/NexxZr-Shine_Highlight-3.4-135x90.png 135w" sizes="(max-width: 960px) 100vw, 960px" />
                                     <p class="slider__secound__description__new"> Paste para superfícies e fissuras </p>
                                         </div>
                                 
                               


           </div>
         </div>
            
          </div>
        
       
       

<script>




jQuery(document).ready(function($) {
   $('.slider__new__cus').slick({
        arrows: false,
        dots:true,
accessibility: false,
     infinite: true,
     slidesToShow: 1,
     variableWidth: true,
  slidesToScroll: 1,
     centerMode: true,
     prevArrow:"<button type='button' class='slick-prev new__slider__first pull-left'><i class='fa fa-angle-left' aria-hidden='true'></i></button>",
      nextArrow:"<button type='button' class='slick-next new__slider__first pull-right'><i class='fa fa-angle-right' aria-hidden='true'></i></button>",
       responsive: [ {
               breakpoint: 1000,
               settings: {
                   slidesToShow: 1,
                   slidesToScroll: 1
               }
           },
           {
               breakpoint: 700,
               settings: {
arrows: false,
                   slidesToShow: 1,
                   slidesToScroll: 1
               }
           }
       ]
   });
});

jQuery(document).ready(function($) {
   $('.secound__slider').slick({
         arrows: true,
        dots:true,
       infinite: true,
       slidesToShow: 1,
       slidesToScroll: 1,
       draggable:false,
       accessibility: false,
       prevArrow:"<button type='button' class='slick-prev new__slider__secound  hide__arrows pull-left'><i class='fa fa-angle-left' aria-hidden='true'></i></button>",
       nextArrow:"<button type='button' class='slick-next new__slider__secound hide__arrows pull-right'><i class='fa fa-angle-right' aria-hidden='true'></i></button>",
       responsive: [ {
               breakpoint: 1000,
               settings: {
                dots: true,
                autoplay:true,
                autoplaySpeed:2000,
                draggable: false,
                swipe: false,
                swipeToSlide: false,
                touchMove: false,
                draggable: false,
               }
           },
           ]
     });
          });
          $=jQuery;


jQuery(document).ready(function($)  {
var newWindowWidth = jQuery(window).width();
        if (newWindowWidth >= 1000) {

            interval = setInterval(function () {
         $(document).ready(function(){
             $(".slick-center .secound__slider .slick-dots li:not(.slick-active)").each(function(i) {
             var btn = $(this);
             var noNext =  $(".slick-center .secound__slider .slick-dots .slick-active").next('li').length;
             if(noNext != 0 ){

      $(".slick-center .slick-next.new__slider__secound.pull-right.slick-arrow").trigger("click");
         } else {

$(".slick-center .slick-next.new__slider__secound.pull-right.slick-arrow").trigger("click");
         }
         });
         });
         }, 3000);

         $('.slider__new__cus ').on('beforeChange', function(event, slick, currentSlide, nextSlide){
         window.clearTimeout(interval);
         interval = setInterval(function () {
      $(document).ready(function(){
          $(".slick-center .secound__slider .slick-dots li:not(.slick-active)").each(function(i) {
          var btn = $(this);
          var noNext =  $(".slick-center .secound__slider .slick-dots .slick-active").next('li').length;
          if(noNext != 0 ){

   $(".slick-center .slick-next.new__slider__secound.pull-right.slick-arrow").trigger("click");
      } else {

$(".slick-center .slick-next.new__slider__secound.pull-right.slick-arrow").trigger("click");
      }
      });
      });
      }, 3000);
         });
       }

        // if (newWindowWidth >=  1000) {

         $('.secound__slider__full__max').click(function(e) {
           var clickedIndex = $(this).parent().parent().index();
           $('.slider__new__cus').slick('slickGoTo', parseInt(clickedIndex -2 ));

         });



           $('.secound__slider').on('afterChange', function(event, slick, currentSlide){
           $('.secound__slider div.slick-active').addClass('was__active');
           var findParent = $(this).find('.was__active');
            if ( !$(findParent).hasClass("was__active")){
             $('.secound__slider').slick('setPosition');
            }
             // if(currentSlide != 0 ){
             //           $('.secound__slider').slick('setPosition');
             // }
           });
           $('.slider__new__cus').on('afterChange', function(event, slick, currentSlide, nextSlide){

             var findParent = $(this).find('div.slick-active').find('.secound__slider').find('div.slick-active');

              if ( !$(findParent).hasClass("was__active")){
;
               $('.secound__slider').slick('setPosition');
              }

          });
       // }


 });


</script>

 <div class="wpb_row vc_row-fluid vc_row standard_section" >
   <div class="testimonials__slider">
       
                <div class="vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding no-left-margin">
         <div class="vc_column-inner spacing__testimonial home__page__spacing">
             <div class="wpb_wrapper">
               <div class="wpb_row vc_row-fluid vc_row standard_section" >
                    <div class="row_col_wrap_12_inner col span_12  left">
                      <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding no-left-margin">
                   <div class="img-with-aniamtion-wrap" data-max-width="100%" data-border-radius="none">
                     <div class="inner image__testimonial__wrapper">
                       <img width="345" height="276" src="https://sagemax.com/wp-content/uploads/2023/03/Ambas11-345x276.jpg" class="attachment-testimonal_equal size-testimonal_equal" alt="" />                     </div>
                   </div>
               </div>
                    <div class="row__testimonial__text vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding no-left-margin">

                      <p class="testimonial__desc__new"><q>Estou convencido da qualidade dos polidores NexxZr Shine devido à sua dureza perfeitamente ajustada, à baixa geração de calor e à sua longa vida útil. O resultado do brilho é magnífico, não apenas em óxido de zircónio.</q></p>
                      <p class="testimonial__title__new"><strong>Michal Nytko</strong>Técnico em Odontologia, Polônia</p>
                 </div>
                 </div>
               </div>
               </div>
             </div>
            </div>




                <div class="vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding no-left-margin">
         <div class="vc_column-inner spacing__testimonial home__page__spacing">
             <div class="wpb_wrapper">
               <div class="wpb_row vc_row-fluid vc_row standard_section" >
                    <div class="row_col_wrap_12_inner col span_12  left">
                      <div class="vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding no-left-margin">
                   <div class="img-with-aniamtion-wrap" data-max-width="100%" data-border-radius="none">
                     <div class="inner image__testimonial__wrapper">
                       <img width="345" height="276" src="https://sagemax.com/wp-content/uploads/2021/03/Ambas9-345x276.jpg" class="attachment-testimonal_equal size-testimonal_equal" alt="" />                     </div>
                   </div>
               </div>
                    <div class="row__testimonial__text vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding no-left-margin">

                      <p class="testimonial__desc__new"><q>NexxZr Shine é um kit de polimento totalmente incrível, com uma pasta de polimento que cria superfícies de alto brilho. O grau de polimento pode ser perfeitamente controlado pela pressão superficial e pela quantidade de pasta.</q></p>
                      <p class="testimonial__title__new"><strong>Vadim Melik</strong>Mestre em técnica odontológica Mevadent, Alemanha</p>
                 </div>
                 </div>
               </div>
               </div>
             </div>
            </div>




       
       
</div>

</div>

<script>
jQuery(document).ready(function($) {
   $('.testimonials__slider').slick({
       dots: true,
       infinite: false,
       speed: 500,
       slidesToShow: 1,
       slidesToScroll: 1,
       autoplay: false,
       autoplaySpeed: 2000,
       arrows: false,
       responsive: [ {
               breakpoint: 1000,
               settings: {
                   slidesToShow: 1,
                   slidesToScroll: 1
               }
           },
           {
               breakpoint: 700,
               settings: {
                   arrows: false,
                   slidesToShow: 1,
                   slidesToScroll: 1
               }
           }
       ]
   });
});

</script>



    </div>
</div>

{"id":688868,"date":"2022-09-13T14:00:07","date_gmt":"2022-09-13T12:00:07","guid":{"rendered":"https:\/\/sagemax.com\/nexxzr-shine\/"},"modified":"2022-10-11T09:40:21","modified_gmt":"2022-10-11T07:40:21","slug":"nexxzr-shine","status":"publish","type":"page","link":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/","title":{"rendered":"NexxZr Shine"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;no__exatra__spacing__pls&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]\n\t\t\t<!-- START NexxZr Shine REVOLUTION SLIDER 6.7.34 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_92_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_92_1\" style=\"\" data-version=\"6.7.34\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-180\" data-title=\"Slide\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/sagemax.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"NexxZr Shine Website Slider\" width=\"2560\" height=\"750\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/sagemax.com\/wp-content\/uploads\/2025\/07\/NexxZr-Shine-Website-Slider-scaled.jpg\" data-bg=\"p:left center;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_92_1',rl:[1240,1024,778,480],el:[580],gw:[1980],gh:[580],type:'hero',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider921\"]!==undefined) {window.RS_MODULES.modules[\"revslider921\"].once = false;window.revapi92 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40px&#8221; top_padding_phone=&#8221;20px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;no__margins__fix&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;product__det__sub__underline&#8221;]NexxZr Shine[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20&#8243; top_padding_phone=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;product__detail__half&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;product__det__title&#8221;]\n<h3>Polimento eficaz.<br \/>\nBrilho natural.<\/h3>\n[\/vc_column_text][vc_column_text el_class=&#8221;justify__text&#8221;]NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas: p. ex. \u00f3xido de zirc\u00f4nio, \u00f3xido de alum\u00ednio, dissilicato de l\u00edtio ou cer\u00e2mica de vidro.<\/p>\n<p>Os polidores de borracha de dimens\u00f5es est\u00e1veis, com diamantes intercalados, impressionam por sua utiliza\u00e7\u00e3o f\u00e1cil e eficiente. Al\u00e9m disso, eles oferecem uma longa durabilidade e um resultado de brilho com apar\u00eancia natural. NexxZr Shine gera uma superf\u00edcie homog\u00eanea tanto em restaura\u00e7\u00f5es monol\u00edticas quanto revestidas ou parcialmente revestidas. Para o polimento ideal das diferentes estruturas e superf\u00edcies, est\u00e3o dispon\u00edveis tr\u00eas formatos compat\u00edveis entre si: Turn 18, Twist 17\u00a0 e Tip 5. Os formatos est\u00e3o dispon\u00edveis nas granula\u00e7\u00f5es smooth (est\u00e1gio 1, pr\u00e9-polimento) e gloss (est\u00e1gio 2, polimento de alto brilho).<\/p>\n<p>O sortimento \u00e9 complementado com a pasta de polimento com diamante de uso universal NexxZr Shine Paste. Ela remove micro-arranh\u00f5es e deixa uma superf\u00edcie espelhada de alto brilho.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;bottom&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;product__detail__half__40&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#d6d6d6&#8243; column_border_style=&#8221;solid&#8221;]\n\t\t\t<!-- START shine REVOLUTION SLIDER 6.7.34 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_93_2_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_93_2\" style=\"\" data-version=\"6.7.34\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-181\" data-title=\"Slide\" data-thumb=\"\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine_Slider-1-50x100.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/sagemax.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"NexxZr Shine_Slider 1\" width=\"510\" height=\"325\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine_Slider-1.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-93-slide-181-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"object\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Roboto';\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-182\" data-title=\"Slide\" data-thumb=\"\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine_Slider-2-50x100.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/sagemax.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"NexxZr Shine_Slider 2\" width=\"510\" height=\"325\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine_Slider-2.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-93-slide-182-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"object\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Roboto';\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-183\" data-title=\"Slide\" data-thumb=\"\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine_Slider-3-50x100.png\" data-anim=\"adpr:false;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/sagemax.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"NexxZr Shine_Slider 3\" width=\"510\" height=\"325\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine_Slider-3.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-93-slide-183-layer-14\" \n\t\t\t\t\t\t\t\tdata-type=\"object\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:50px;y:50px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Roboto';\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_93_2',rl:[1240,1024,778,480],el:[350],gw:[550],gh:[350],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider932\"]!==undefined) {window.RS_MODULES.modules[\"revslider932\"].once = false;window.revapi93 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;50px&#8221; left_padding_desktop=&#8221;30px&#8221; right_padding_desktop=&#8221;30px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;mobile__50__products&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;price__product__detail&#8221;]NexxZr Shine[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;mobile__50__products&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#dadada&#8221; solid_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;button__buy__product__over&#8221; url=&#8221;https:\/\/sagemax.com\/pt-pt\/dealer\/&#8221; text=&#8221;Compre agora &#8221; css_animation=&#8221;pulse&#8221; margin_top=&#8221;20&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;47px&#8221; bottom_padding=&#8221;50px&#8221; top_padding_phone=&#8221;30px&#8221; bottom_padding_phone=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;no__margins__fix&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;subtitle__new__product__p&#8221;]Dados t\u00e9cnicos[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding_phone=&#8221;15px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;mobile__fix__zero__bottom&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;icons__width__row__np&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;688644&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_left=&#8221;25%&#8221; margin_right=&#8221;25%&#8221;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Tipo<br \/>\n<\/strong>Sistema de polimento com<br \/>\ndiamante em dois est\u00e1gios<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;icons__width__row__np&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;688662&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_left=&#8221;25%&#8221; margin_right=&#8221;25%&#8221;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Material<br \/>\n<\/strong>Polidor de borracha com<br \/>\ndiamantes intercalados<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;icons__width__row__np&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;688635&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_left=&#8221;25%&#8221; margin_right=&#8221;25%&#8221;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Granula\u00e7\u00f5es<br \/>\n<\/strong>smooth, gloss<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;icons__width__row__np&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;688653&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_left=&#8221;25%&#8221; margin_right=&#8221;25%&#8221;][vc_column_text]\n<p style=\"text-align: center;\"><strong>Adequado para<\/strong><br \/>\ntodas as cer\u00e2micas<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;icons__width__row__np&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;688626&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_left=&#8221;25%&#8221; margin_right=&#8221;25%&#8221;][vc_column_text]\n<p style=\"text-align: center;\"><strong>3 formatos, 1 pasta<br \/>\n<\/strong>Turn 18, Twist 17, Tip 5, pasta<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;45&#8243; bottom_padding=&#8221;50&#8243; bottom_padding_phone=&#8221;30px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/youtu.be\/x8Ax8wgnYDU&#8221; el_width=&#8221;60&#8243; align=&#8221;center&#8221; el_class=&#8221;mobile__iframe__tempnxr&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;30px&#8221; bottom_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;mobile__fix__zero__bottom&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;subtitle__new__product__p highlights__space&#8221;]Destaques[\/vc_column_text][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f2f2f2&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;20&#8243; bottom_padding=&#8221;20&#8243; top_padding_phone=&#8221;40px&#8221; bottom_padding_phone=&#8221;40px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;banner__new__product__ovr&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;12071&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;image__inline__banner&#8221;][vc_column_text el_class=&#8221;text__inline__banner&#8221;]Compre NexxZr Shine agora[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;button__inline__banner&#8221; text=&#8221;Shop&#8221; url=&#8221;https:\/\/sagemax.com\/pt-pt\/dealer\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;70px&#8221; bottom_padding=&#8221;00px&#8221; top_padding_phone=&#8221;50px&#8221; bottom_padding_phone=&#8221;10px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;subtitle__new__product__p&#8221;]Brand Ambassador[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; translate_y=&#8221;-50px&#8221; translate_y_phone=&#8221;-20px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;left&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;extra-color-2&#8243; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Downloads&#8221; id=&#8221;1665141362885-1&#8243; tab_id=&#8221;1665141362886-3&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;margin__bottom__row__mobile__product&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<a class=\"go__to__download__sec\" href=\"https:\/\/eifu.sagemax.com\/\" target=\"_blank\" rel=\"noopener\"> SAGEMAX INSTRUCTIONS FOR USE PORTAL <\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Informa\u00e7\u00e3o sobre o produto&#8221; id=&#8221;1665141363066-0&#8243; tab_id=&#8221;1665141363069-7&#8243; el_class=&#8221;tab__custom__width&#8221;][vc_column_text]NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.<\/p>\n<p><strong>Formatos de fornecimento:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>NexxZr Shine Starter Kit\u00a0<\/strong><br \/>\nTurn 18 smooth<br \/>\nTurn 18 gloss<br \/>\nTwist 17 smooth<br \/>\nTwist 17 gloss<br \/>\nTip 5 smooth<br \/>\nTip 5 gloss<br \/>\nPaste 20 g<\/p>\n<p><strong>NexxZr Shine Polishing Kit<\/strong><br \/>\nTurn 18 smooth<br \/>\nTurn 18 gloss<br \/>\nTwist 17 smooth<br \/>\nTwist 17 gloss<br \/>\nTip 5 smooth<br \/>\nTip 5 gloss<\/p>\n<p><strong>Refil\u00a0<\/strong><br \/>\nNexxZr Shine Turn 18 smooth<br \/>\nNexxZr Shine Turn 18 gloss<br \/>\nNexxZr Shine Twist 17 smooth<br \/>\nNexxZr Shine Twist 17 gloss<br \/>\nNexxZr Shine Tip 5 smooth<br \/>\nNexxZr Shine Tip 5 gloss<br \/>\nNexxZr Shine Paste 20 g[\/vc_column_text][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;V\u00eddeos&#8221; id=&#8221;1665141363110-9&#8243; tab_id=&#8221;1665141363112-2&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/youtu.be\/x8Ax8wgnYDU&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0px&#8221; bottom_padding=&#8221;50px&#8221; top_padding_phone=&#8221;10px&#8221; bottom_padding_phone=&#8221;10px&#8221; translate_y=&#8221;-20px&#8221; translate_y_tablet=&#8221;-23px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;no__margins__fix&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;subtitle__new__product__p&#8221;]Por favor contacte-me[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;40px&#8221; bottom_padding_phone=&#8221;0&#8243; translate_y=&#8221;-20px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;contact&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<div class=\"forminator-ui forminator-custom-form forminator-custom-form-14211 forminator-design--flat forminator-custom forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-14211\" data-uid=\"6a56f73408677\"><br\/><\/div><form\r\n\t\t\t\tid=\"forminator-module-14211\"\r\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-14211 forminator-design--flat forminator-custom forminator_ajax\"\r\n\t\t\t\tmethod=\"post\"\r\n\t\t\t\tdata-forminator-render=\"0\"\r\n\t\t\t\tdata-form-id=\"14211\"\r\n\t\t\t\t data-color-option=\"default\" data-design=\"flat\" data-grid=\"custom\" style=\"display: none;\"\r\n\t\t\t\tdata-uid=\"6a56f73408677\"\r\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-12  half__form\"><div class=\"forminator-field\"><label for=\"forminator-field-name-1_6a56f73408677\" id=\"forminator-field-name-1_6a56f73408677-label\" class=\"forminator-label\">Nome <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1\" value=\"\" placeholder=\"Insira o seu nome\" id=\"forminator-field-name-1_6a56f73408677\" class=\"forminator-input forminator-name--field\" aria-required=\"true\" autocomplete=\"name\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12  half__form\"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a56f73408677\" id=\"forminator-field-email-1_6a56f73408677-label\" class=\"forminator-label\">E-Mail <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"Insira o seu endere\u00e7o de e-mail\" id=\"forminator-field-email-1_6a56f73408677\" class=\"forminator-input forminator-email--field\" data-required=\"true\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-1\" class=\"forminator-field-phone forminator-col forminator-col-12  half__form\"><div class=\"forminator-field\"><label for=\"forminator-field-phone-1_6a56f73408677\" id=\"forminator-field-phone-1_6a56f73408677-label\" class=\"forminator-label\">Celular <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"phone-1\" value=\"\" placeholder=\"Insira o seu n\u00famero de telefone\" id=\"forminator-field-phone-1_6a56f73408677\" class=\"forminator-input forminator-field--phone\" data-required=\"1\" aria-required=\"true\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"text-1\" class=\"forminator-field-text forminator-col forminator-col-12  half__form half__form conuntry__100\"><div class=\"forminator-field\"><label for=\"forminator-field-text-1_6a56f73408677\" id=\"forminator-field-text-1_6a56f73408677-label\" class=\"forminator-label\">Pais<\/label><input type=\"text\" name=\"text-1\" value=\"\" placeholder=\"Insira o seu pais\" id=\"forminator-field-text-1_6a56f73408677\" class=\"forminator-input forminator-name--field\" data-required=\"\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"textarea-1\" class=\"forminator-field-textarea forminator-col forminator-col-12  half__form__message\"><div class=\"forminator-field\"><textarea name=\"textarea-1\" placeholder=\"Digite a mensagem...\" id=\"forminator-field-textarea-1_6a56f73408677\" class=\"forminator-textarea\" style=\"--forminator-textarea-min-height:162px;\" maxlength=\"750\" ><\/textarea><span id=\"forminator-field-textarea-1_6a56f73408677-description\" class=\"forminator-description\"><span data-limit=\"750\" data-type=\"characters\" data-editor=\"\">0 \/ 750<\/span><\/span><\/div><\/div><\/div><div class=\"forminator-row forminator-hidden\"><div id=\"hidden-1\" class=\"forminator-field-hidden  forminator-col-12 \"><input type=\"hidden\" id=\"hidden-1_6a56f73408677\" name=\"hidden-1\" value=\"https:\/\/sagemax.com\/pt-pt\/testimonials\/vadim-melikmestre-em-tecnica-odontologica-mevadent-alemanha-2\/\" \/><\/div><\/div><div class=\"forminator-row\"><div id=\"captcha-1\" class=\"forminator-field-captcha forminator-col forminator-col-12 \"><div class=\"forminator-captcha-left forminator-g-recaptcha recaptcha-invisible\" data-theme=\"light\" data-badge=\"inline\" data-sitekey=\"6LcQ7tkcAAAAAPbIeNDyMvyRWJXVUPz_DTcfWZ0E\" data-size=\"invisible\"><\/div> <\/div><\/div><div class=\"forminator-row\"><div id=\"consent-1\" class=\"forminator-field-consent forminator-col forminator-col-12 \"><div class=\"forminator-field\"><div class=\"forminator-checkbox__wrapper\"><label id=\"forminator-field-consent-1_6a56f73408677__label\" class=\"forminator-checkbox forminator-consent\"><input type=\"checkbox\" name=\"consent-1\" id=\"forminator-field-consent-1_6a56f73408677\" value=\"checked\" aria-labelledby=\"forminator-field-consent-1_6a56f73408677-label\" aria-describedby=\"forminator-field-consent-1_6a56f73408677__description\" data-required=\"true\" aria-required=\"true\" \/><span class=\"forminator-checkbox-box\" aria-hidden=\"true\"><\/span><\/label><div id=\"forminator-field-consent-1_6a56f73408677__description\" class=\"forminator-checkbox__label forminator-consent__label\"><p>Confirmo que li e aceitei a <a rel=\"noopener\" target=\"_blank\" href=\"\/datenschutz\">Pol\u00edtica de Privacidade<\/a>.<\/p><\/div><\/div><\/div><\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">ENVIAR<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"2066f2b5f3\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/pt-pt\/wp-json\/wp\/v2\/pages\/688868\" \/><input type=\"hidden\" name=\"form_id\" value=\"14211\"><input type=\"hidden\" name=\"page_id\" value=\"688975\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"https:\/\/sagemax.com\/pt-pt\/testimonials\/vadim-melikmestre-em-tecnica-odontologica-mevadent-alemanha-2\/\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><label for=\"input_8\" class=\"forminator-hidden\" aria-hidden=\"true\">Please do not fill in this field. <input id=\"input_8\" type=\"text\" name=\"input_8\" value=\"\" autocomplete=\"off\"><\/label><\/form>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;no__exatra__spacing__pls&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243;&#8230;<\/p>\n","protected":false},"author":4,"featured_media":688503,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-688868","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NexxZr Shine - Sagemax\u00ae<\/title>\n<meta name=\"description\" content=\"NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NexxZr Shine\" \/>\n<meta property=\"og:description\" content=\"NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/\" \/>\n<meta property=\"og:site_name\" content=\"Sagemax\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sagemax.official\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-11T07:40:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine-Polishing-Kit_white_open.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/\",\"url\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/\",\"name\":\"NexxZr Shine - Sagemax\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sagemax.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/NexxZr-Shine-Polishing-Kit_white_open.png\",\"datePublished\":\"2022-09-13T12:00:07+00:00\",\"dateModified\":\"2022-10-11T07:40:21+00:00\",\"description\":\"NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sagemax.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/NexxZr-Shine-Polishing-Kit_white_open.png\",\"contentUrl\":\"https:\\\/\\\/sagemax.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/NexxZr-Shine-Polishing-Kit_white_open.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/nexxzr-shine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/home-page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NexxZr Shine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/\",\"name\":\"Sagemax\u00ae\",\"description\":\"Dental esthetics with zirconium\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sagemax.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NexxZr Shine - Sagemax\u00ae","description":"NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/","og_locale":"pt_PT","og_type":"article","og_title":"NexxZr Shine","og_description":"NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.","og_url":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/","og_site_name":"Sagemax\u00ae","article_publisher":"https:\/\/www.facebook.com\/sagemax.official","article_modified_time":"2022-10-11T07:40:21+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine-Polishing-Kit_white_open.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/","url":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/","name":"NexxZr Shine - Sagemax\u00ae","isPartOf":{"@id":"https:\/\/sagemax.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/#primaryimage"},"image":{"@id":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/#primaryimage"},"thumbnailUrl":"https:\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine-Polishing-Kit_white_open.png","datePublished":"2022-09-13T12:00:07+00:00","dateModified":"2022-10-11T07:40:21+00:00","description":"NexxZr Shine \u00e9 um sistema de polimento com diamante em dois est\u00e1gios para o polimento eficaz de cer\u00e2micas odontol\u00f3gicas.","breadcrumb":{"@id":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/#primaryimage","url":"https:\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine-Polishing-Kit_white_open.png","contentUrl":"https:\/\/sagemax.com\/wp-content\/uploads\/2022\/09\/NexxZr-Shine-Polishing-Kit_white_open.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/sagemax.com\/pt-pt\/nexxzr-shine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sagemax.com\/pt-pt\/home-page\/"},{"@type":"ListItem","position":2,"name":"NexxZr Shine"}]},{"@type":"WebSite","@id":"https:\/\/sagemax.com\/pt-pt\/#website","url":"https:\/\/sagemax.com\/pt-pt\/","name":"Sagemax\u00ae","description":"Dental esthetics with zirconium","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sagemax.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/pages\/688868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=688868"}],"version-history":[{"count":12,"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/pages\/688868\/revisions"}],"predecessor-version":[{"id":689837,"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/pages\/688868\/revisions\/689837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/media\/688503"}],"wp:attachment":[{"href":"https:\/\/sagemax.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=688868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}